{"id":9,"date":"2021-04-09T09:27:07","date_gmt":"2021-04-09T09:27:07","guid":{"rendered":"https:\/\/www.chisagess.de\/index.php\/about\/"},"modified":"2025-10-21T07:46:13","modified_gmt":"2025-10-21T05:46:13","slug":"about-us","status":"publish","type":"page","link":"https:\/\/chisagepolska.pl\/index.php\/about-us\/","title":{"rendered":"O nas"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"9\" class=\"elementor elementor-9\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2976d82 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"2976d82\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_bottom&quot;:&quot;curve&quot;,&quot;shape_divider_bottom_negative&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"true\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M500,97C126.7,96.3,0.8,19.8,0,0v100l1000,0V1C1000,19.4,873.3,97.8,500,97z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5ef8ce3\" data-id=\"5ef8ce3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f31de1 elementor-widget elementor-widget-heading\" data-id=\"7f31de1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-xl\">Poznaj grup\u0119 CHISAGE<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c9d6ddd elementor-widget elementor-widget-text-editor\" data-id=\"c9d6ddd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Top 500 Prywatnych Firm w Chinach<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53918dc elementor-widget__width-initial elementor-widget elementor-widget-video\" data-id=\"53918dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/JVXrJxsLKR4?si=vldH4-zbkqR0g2Uk&quot;,&quot;show_image_overlay&quot;:&quot;yes&quot;,&quot;image_overlay&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/chisagepolska.pl\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/CHISAGE-Group-Einfuhrungsvideo-2-e1701238052534.png&quot;,&quot;id&quot;:20703,&quot;size&quot;:&quot;&quot;},&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t\t\t<div class=\"elementor-custom-embed-image-overlay\" style=\"background-image: url(https:\/\/chisagepolska.pl\/wp-content\/uploads\/2024\/06\/CHISAGE-Group-Einfuhrungsvideo-2-e1701238052534.png);\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-custom-embed-play\" role=\"button\" aria-label=\"\u64ad\u653e\u89c6\u9891\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-play\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-25b2a26 e-con-full e-flex e-con e-parent\" data-id=\"25b2a26\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4d9da85 elementor-widget elementor-widget-image\" data-id=\"4d9da85\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1920\" height=\"675\" src=\"https:\/\/chisagepolska.pl\/wp-content\/uploads\/2024\/06\/CHISAGE-Headquarters-building-41.jpg\" class=\"attachment-full size-full wp-image-20705\" alt=\"\" srcset=\"https:\/\/chisagepolska.pl\/wp-content\/uploads\/2024\/06\/CHISAGE-Headquarters-building-41.jpg 1920w, https:\/\/chisagepolska.pl\/wp-content\/uploads\/2024\/06\/CHISAGE-Headquarters-building-41-300x105.jpg 300w, https:\/\/chisagepolska.pl\/wp-content\/uploads\/2024\/06\/CHISAGE-Headquarters-building-41-1024x360.jpg 1024w, https:\/\/chisagepolska.pl\/wp-content\/uploads\/2024\/06\/CHISAGE-Headquarters-building-41-768x270.jpg 768w, https:\/\/chisagepolska.pl\/wp-content\/uploads\/2024\/06\/CHISAGE-Headquarters-building-41-1536x540.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a7aadb9 e-flex e-con-boxed e-con e-child\" data-id=\"a7aadb9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f57b103 elementor-widget elementor-widget-heading\" data-id=\"f57b103\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">O Chisage Polska<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1d594e9 e-flex e-con-boxed e-con e-child\" data-id=\"1d594e9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f4eed43 elementor-widget elementor-widget-text-editor\" data-id=\"f4eed43\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Jako sp\u00f3\u0142ka zale\u017cna Chisage ESS, \u015bwiatowego lidera w dziedzinie rozwi\u0105za\u0144 w zakresie magazynowania energii, nasz\u0105 misj\u0105 w Chisage Polska jest u\u0142atwienie przej\u015bcia na czyst\u0105 energi\u0119 w Polsce i poza ni\u0105, wspieranie dom\u00f3w, przedsi\u0119biorstw i przemys\u0142u przy jednoczesnym nap\u0119dzaniu przyj\u0119cia energii odnawialnej w ca\u0142ej Europie.<\/p><h3 style=\"text-align: center;\">Nasza Misja<\/h3><p>Staramy si\u0119, aby magazynowanie energii by\u0142o wydajne, niezawodne i przyjazne dla \u015brodowiska, wspieraj\u0105c przej\u015bcie na odnawialne \u017ar\u00f3d\u0142a energii i zwi\u0119kszaj\u0105c zar\u00f3wno zr\u00f3wnowa\u017cony rozw\u00f3j \u015brodowiskowy, jak i bezpiecze\u0144stwo energetyczne.<\/p><h3 style=\"text-align: center;\">Nasza Wizja<\/h3><p>Nasz\u0105 wizj\u0105 jest przewodzenie Europie w dostarczaniu innowacyjnych, wysokiej jako\u015bci rozwi\u0105za\u0144 w zakresie magazynowania energii, stymulowanie wzrostu gospodarczego, zr\u00f3wnowa\u017cenia \u015brodowiskowego i globalnego przej\u015bcia na energi\u0119 odnawialn\u0105 poprzez ci\u0105g\u0142e badania i rozw\u00f3j.<\/p><h3 style=\"text-align: center;\">Strategia Marketingowa<\/h3><p>Nasza strategia marketingowa w Chisage Polska opiera si\u0119 na tworzeniu warto\u015bci dla klienta i budowaniu trwa\u0142ych relacji. Stawiaj\u0105c na pierwszym miejscu potrzeby klient\u00f3w, dostarczaj\u0105c innowacyjne i zr\u00f3wnowa\u017cone rozwi\u0105zania oraz tworz\u0105c strategiczne partnerstwa, d\u0105\u017cymy do edukacji i wzmocnienia pozycji spo\u0142eczno\u015bci w ca\u0142ej Europie w ich przej\u015bciu na energi\u0119 odnawialn\u0105. Dzi\u0119ki lokalnym dzia\u0142aniom marketingowym zapewniamy, \u017ce nasze rozwi\u0105zania trafiaj\u0105 do r\u00f3\u017cnych odbiorc\u00f3w, przyczyniaj\u0105c si\u0119 do bardziej ekologicznej i zr\u00f3wnowa\u017conej przysz\u0142o\u015bci.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e922085 e-con-full e-flex e-con e-parent\" data-id=\"e922085\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-c09b01d e-flex e-con-boxed e-con e-child\" data-id=\"c09b01d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ff6b856 elementor-widget elementor-widget-heading\" data-id=\"ff6b856\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Poznaj Ekspert\u00f3w ds. Energii<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2537083 e-flex e-con-boxed e-con e-child\" data-id=\"2537083\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-cf0e682 e-flex e-con-boxed e-con e-child\" data-id=\"cf0e682\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-73958f3 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"73958f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/chisagepolska.pl\/wp-content\/uploads\/2024\/06\/Herong-Yang.jpg\" class=\"attachment-full size-full wp-image-20760\" alt=\"Herong Yang\" srcset=\"https:\/\/chisagepolska.pl\/wp-content\/uploads\/2024\/06\/Herong-Yang.jpg 1000w, https:\/\/chisagepolska.pl\/wp-content\/uploads\/2024\/06\/Herong-Yang-300x300.jpg 300w, https:\/\/chisagepolska.pl\/wp-content\/uploads\/2024\/06\/Herong-Yang-150x150.jpg 150w, https:\/\/chisagepolska.pl\/wp-content\/uploads\/2024\/06\/Herong-Yang-768x768.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Herong Yang<\/h3><p class=\"elementor-image-box-description\">Przez ca\u0142y czas Chisage zawsze przestrzega\u0142 filozofii biznesowej \" najpierw klient, potem realizacja, synergiczna innowacja i utrzymanie ducha ci\u0119\u017ckiej pracy i prostoty<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dcb6c8c e-flex e-con-boxed e-con e-child\" data-id=\"dcb6c8c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-78eef7a elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"78eef7a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/chisagepolska.pl\/wp-content\/uploads\/2024\/06\/Bin-Chen1.jpg\" class=\"attachment-full size-full wp-image-20759\" alt=\"Bin Chen(1)\" srcset=\"https:\/\/chisagepolska.pl\/wp-content\/uploads\/2024\/06\/Bin-Chen1.jpg 1000w, https:\/\/chisagepolska.pl\/wp-content\/uploads\/2024\/06\/Bin-Chen1-300x300.jpg 300w, https:\/\/chisagepolska.pl\/wp-content\/uploads\/2024\/06\/Bin-Chen1-150x150.jpg 150w, https:\/\/chisagepolska.pl\/wp-content\/uploads\/2024\/06\/Bin-Chen1-768x768.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Bin Chen<\/h3><p class=\"elementor-image-box-description\">Pan Chen wnosi ponad 10-letnie do\u015bwiadczenie w sektorze energii odnawialnej, nap\u0119dzaj\u0105c firm\u0119 w kierunku doskona\u0142o\u015bci i innowacji. Jego wizjonerskie przyw\u00f3dztwo i zaanga\u017cowanie w zr\u00f3wnowa\u017cony rozw\u00f3j sprawi\u0142y, \u017ce Chisage ESS znalaz\u0142 si\u0119 w czo\u0142\u00f3wce bran\u017cy magazynowania energii.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9f7439e e-flex e-con-boxed e-con e-child\" data-id=\"9f7439e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bd96537 elementor-widget elementor-widget-text-editor\" data-id=\"bd96537\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><strong>Do\u0142\u0105cz do zespo\u0142u Chisage ESS Polska!<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-08c3137 e-con-full e-flex e-con e-parent\" data-id=\"08c3137\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:20710,&quot;url&quot;:&quot;https:\\\/\\\/chisagepolska.pl\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/CHISAGE-ESS-Hauptgebaude-Fotos-4-e1701242785329.jpg&quot;}],&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-98f1ab9 elementor-widget__width-initial elementor-widget elementor-widget-n-accordion\" data-id=\"98f1ab9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;expanded&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1600\" class=\"e-n-accordion-item\" open>\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"true\" aria-controls=\"e-n-accordion-item-1600\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> 1998 <\/div><\/span>\n\t\t\t\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1600\" class=\"elementor-element elementor-element-70300dc e-con-full e-flex e-con e-child\" data-id=\"70300dc\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1600\" class=\"elementor-element elementor-element-4452315 e-flex e-con-boxed e-con e-child\" data-id=\"4452315\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6cc950b elementor-widget elementor-widget-text-editor\" data-id=\"6cc950b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Za\u0142o\u017cenie Ningbo U&amp;K Fashion Co., Ltd, poprzednika Ningbo Chisage Holdings Co., Ltd.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1601\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1601\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> 2008 <\/div><\/span>\n\t\t\t\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1601\" class=\"elementor-element elementor-element-9fb6256 e-con-full e-flex e-con e-child\" data-id=\"9fb6256\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1601\" class=\"elementor-element elementor-element-06bdbfe e-flex e-con-boxed e-con e-child\" data-id=\"06bdbfe\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ea2b82e elementor-widget elementor-widget-text-editor\" data-id=\"ea2b82e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sichuan Chisage New Material Technology Co., Ltd. jest dostawc\u0105 materia\u0142\u00f3w elektronicznych, materia\u0142\u00f3w anodowych, tlenku manganu i siarczanu manganu o wysokiej czysto\u015bci. Nale\u017c\u0119 do projekt\u00f3w Aiding Sichuan organizowanych przez kupc\u00f3w z Zhejiang w celu odbudowy i przywr\u00f3cenia \u017ar\u00f3de\u0142 utrzymania i gospodarki w Qingchuan po trz\u0119sieniu ziemi z 12 maja. Mo\u017ce wspiera\u0107.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1602\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1602\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> 2014 <\/div><\/span>\n\t\t\t\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1602\" class=\"elementor-element elementor-element-5409c37 e-con-full e-flex e-con e-child\" data-id=\"5409c37\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1602\" class=\"elementor-element elementor-element-db9fdec e-flex e-con-boxed e-con e-child\" data-id=\"db9fdec\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9b80382 elementor-widget elementor-widget-text-editor\" data-id=\"9b80382\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div id=\"page\" class=\"hfeed site\"><div id=\"content\" class=\"site-content\"><div class=\"ast-container\"><div id=\"primary\" class=\"content-area primary\"><p>Powsta\u0142a firma Jiangsu Chisage Carbon Photonics Research and Development Center Co., kt\u00f3ra koncentruje si\u0119 na produkcji i sprzeda\u017cy nowych technologii biomedycznych oraz przej\u0119ciu \u015bwiatowego lidera w dziedzinie zielonej fototerapii.<\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1603\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1603\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> 2017 <\/div><\/span>\n\t\t\t\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1603\" class=\"elementor-element elementor-element-f6e7116 e-flex e-con-boxed e-con e-child\" data-id=\"f6e7116\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1603\" class=\"elementor-element elementor-element-07277ad e-flex e-con-boxed e-con e-child\" data-id=\"07277ad\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ba95589 elementor-widget elementor-widget-text-editor\" data-id=\"ba95589\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sp\u00f3\u0142ka Ningbo Chisage Resource Co. Ltd. zosta\u0142a za\u0142o\u017cona pod patronatem Chisage Group i koncentruje si\u0119 na platformie biznesowej do handlu towarami masowymi. Nazwa Zhejiang Chisage Holding Group Co., Ltd. zosta\u0142a zmieniona na Chisage Holding Group Co., Ltd. Firma Beijing Ounlitiancheng Network Technologist Co., Ltd. sta\u0142a si\u0119 sp\u00f3\u0142k\u0105 zale\u017cn\u0105 Chisage Group i jest zorientowan\u0105 na innowacje firm\u0105 technologiczn\u0105, specjalizuj\u0105c\u0105 si\u0119 w wysokiej jako\u015bci produktach audio .<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1604\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"5\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1604\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> 2021 <\/div><\/span>\n\t\t\t\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1604\" class=\"elementor-element elementor-element-b092541 e-flex e-con-boxed e-con e-child\" data-id=\"b092541\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1604\" class=\"elementor-element elementor-element-43a3489 e-flex e-con-boxed e-con e-child\" data-id=\"43a3489\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1f0525d elementor-widget elementor-widget-text-editor\" data-id=\"1f0525d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Zhejiang Jingyan Shenlan New Energy Technology Co., Ltd. zosta\u0142a cz\u0142onkiem Chisage Group. Firma anga\u017cuje si\u0119 w industrializacj\u0119 wysokowydajnych akumulator\u00f3w z wodnym elektrolitem wt\u00f3rnym i obecnie promuje g\u0142\u00f3wnie wolnobie\u017cne w\u00f3zki wid\u0142owe i now\u0105 elektrowni\u0119 magazynuj\u0105c\u0105 energi\u0119. Zhejiang Chisage New Energy Technology Co., Ltd. jest integratorem i inwestorem rozwi\u0105za\u0144 z zakresu magazynowania energii i inteligentnych system\u00f3w specjalizuj\u0105cym si\u0119 w integracji nowych akumulator\u00f3w wodnych, modu\u0142\u00f3w, pakiet\u00f3w, stojak\u00f3w i rozwi\u0105za\u0144 integracyjnych.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1605\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"6\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1605\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> 2024 <\/div><\/span>\n\t\t\t\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1605\" class=\"elementor-element elementor-element-824421b e-flex e-con-boxed e-con e-child\" data-id=\"824421b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1605\" class=\"elementor-element elementor-element-7ac9d5c e-flex e-con-boxed e-con e-child\" data-id=\"7ac9d5c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-211885b elementor-widget elementor-widget-text-editor\" data-id=\"211885b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Za\u0142o\u017cona w kwietniu 2024 roku firma Chisage Polska jest europejskim oddzia\u0142em Chisage ESS. Nasz\u0105 misj\u0105 jest dostarczanie europejskim firmom technologii ESS i B ESS oraz wsparcia technicznego, marketingowego i sprzeda\u017cowego w celu osi\u0105gni\u0119cia rozwoju technologicznego i biznesowego.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1606\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"7\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1606\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Przysz\u0142o\u015b\u0107 <\/div><\/span>\n\t\t\t\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1606\" class=\"elementor-element elementor-element-0f7b18a e-flex e-con-boxed e-con e-child\" data-id=\"0f7b18a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1606\" class=\"elementor-element elementor-element-ea6b4b8 e-flex e-con-boxed e-con e-child\" data-id=\"ea6b4b8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a76d088 elementor-widget elementor-widget-text-editor\" data-id=\"a76d088\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Along the way, CHISAGE has pushed its cause forward and advanced into the future. With customer orientation as a guideline, aspiration, the spirit of hard work and a simple life as a consistent pursuit, it is determined to be a group company both in industry and in the field of industrial investment that continuously creates value.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3969c0a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3969c0a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dab7279\" data-id=\"dab7279\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-38f49fb e-flex e-con-boxed e-con e-parent\" data-id=\"38f49fb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4a01bb5 elementor-widget elementor-widget-heading\" data-id=\"4a01bb5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Znajd\u017a nas na mapie<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5d40f25 e-flex e-con-boxed e-con e-parent\" data-id=\"5d40f25\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-abb56f7 elementor-widget elementor-widget-image\" data-id=\"abb56f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"700\" src=\"https:\/\/chisagepolska.pl\/wp-content\/uploads\/2024\/07\/CHISAGE-Address-22.jpg\" class=\"attachment-large size-large wp-image-20891\" alt=\"CHISAGE Address-2(2)\" srcset=\"https:\/\/chisagepolska.pl\/wp-content\/uploads\/2024\/07\/CHISAGE-Address-22.jpg 1000w, https:\/\/chisagepolska.pl\/wp-content\/uploads\/2024\/07\/CHISAGE-Address-22-300x210.jpg 300w, https:\/\/chisagepolska.pl\/wp-content\/uploads\/2024\/07\/CHISAGE-Address-22-768x538.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1b8d42 elementor-widget elementor-widget-image\" data-id=\"e1b8d42\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/chisagepolska.pl\/wp-content\/uploads\/2024\/06\/CHISAGE-Address-11.jpg\" class=\"attachment-full size-full wp-image-20712\" alt=\"\" srcset=\"https:\/\/chisagepolska.pl\/wp-content\/uploads\/2024\/06\/CHISAGE-Address-11.jpg 1000w, https:\/\/chisagepolska.pl\/wp-content\/uploads\/2024\/06\/CHISAGE-Address-11-300x300.jpg 300w, https:\/\/chisagepolska.pl\/wp-content\/uploads\/2024\/06\/CHISAGE-Address-11-150x150.jpg 150w, https:\/\/chisagepolska.pl\/wp-content\/uploads\/2024\/06\/CHISAGE-Address-11-768x768.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Poznaj grup\u0119 CHISAGE Top 500 Prywatnych Firm w Chinach  [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"unboxed","site-sidebar-style":"unboxed","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"disabled","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"enabled","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-9","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/chisagepolska.pl\/index.php\/wp-json\/wp\/v2\/pages\/9","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chisagepolska.pl\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/chisagepolska.pl\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/chisagepolska.pl\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chisagepolska.pl\/index.php\/wp-json\/wp\/v2\/comments?post=9"}],"version-history":[{"count":144,"href":"https:\/\/chisagepolska.pl\/index.php\/wp-json\/wp\/v2\/pages\/9\/revisions"}],"predecessor-version":[{"id":21319,"href":"https:\/\/chisagepolska.pl\/index.php\/wp-json\/wp\/v2\/pages\/9\/revisions\/21319"}],"wp:attachment":[{"href":"https:\/\/chisagepolska.pl\/index.php\/wp-json\/wp\/v2\/media?parent=9"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}